{"id":799,"date":"2021-10-01T09:51:28","date_gmt":"2021-10-01T12:51:28","guid":{"rendered":"https:\/\/institucional.nutrirsaudestore.com.br\/?p=799"},"modified":"2021-10-01T09:51:28","modified_gmt":"2021-10-01T12:51:28","slug":"hipocloridria-como-evitar-suas-complicacoes-atraves-da-nutricao-na-terceira-idade","status":"publish","type":"post","link":"https:\/\/nutrirsaudestore.com.br\/institucional\/hipocloridria-como-evitar-suas-complicacoes-atraves-da-nutricao-na-terceira-idade\/","title":{"rendered":"Hipocloridria: como evitar suas complica\u00e7\u00f5es atrav\u00e9s da nutri\u00e7\u00e3o na terceira idade"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Por: Raissa Astolpho<\/span><\/p>\n<p><em><strong>Saiba o que \u00e9 hipocloridria, seus sintomas e como evitar o seu surgimento atrav\u00e9s de uma boa nutri\u00e7\u00e3o na terceira idade<\/strong><\/em><\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00ea j\u00e1 ouviu falar sobre hipocloridria? Aquela sensa\u00e7\u00e3o de queima\u00e7\u00e3o e mal estar no est\u00f4mago pode ser definida pelo termo. Ela \u00e9 caracterizada pela diminui\u00e7\u00e3o da produ\u00e7\u00e3o de \u00e1cido clor\u00eddrico, fazendo com que o pH estomacal fique mais alto e leve ao aparecimento de alguns sintomas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 comum surgir na terceira idade, mas pode estar presente em todas as fases da vida. Mesmo assim, pode ser evitada atrav\u00e9s da nutri\u00e7\u00e3o adequada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Continue aqui e entenda mais sobre este assunto!<\/span><\/p>\n<p><b>O corpo e o organismo no processo de envelhecimento\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A senesc\u00eancia, ou seja, o processo natural do envelhecimento, submete o organismo a diversas altera\u00e7\u00f5es anat\u00f4micas, funcionais, metab\u00f3licas e psicol\u00f3gicas, onde todas elas comprometem a alimenta\u00e7\u00e3o e o organismo como um todo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Perda de peso involunt\u00e1ria, redu\u00e7\u00e3o do apetite e caquexia (perda de gordura e musculatura esquel\u00e9tica) s\u00e3o comuns na popula\u00e7\u00e3o geri\u00e1trica, sendo de extrema import\u00e2ncia o conhecimento dos fatores associados ao comprometimento do estado nutricional do idoso.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Um dos fatores relacionados \u00e0 redu\u00e7\u00e3o do consumo alimentar nessa popula\u00e7\u00e3o \u00e9 a falta de motiva\u00e7\u00e3o para se alimentar, sendo que as principais causas relacionadas a esta desmotiva\u00e7\u00e3o s\u00e3o: fisiopatol\u00f3gicas, sociais ou psicol\u00f3gicas ou, ainda, a combina\u00e7\u00e3o entre elas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fatores f\u00edsicos como edentulismo (falta total ou parcial dos dentes), uso de pr\u00f3teses mal adaptadas, mudan\u00e7as no paladar e\/ou olfato, influenciam a escolha da alimenta\u00e7\u00e3o tanto em qualidade quanto em quantidade. Medicamentos relacionados com altera\u00e7\u00f5es no paladar (como por exemplo os anti-hipertensivos) e m\u00e1 absor\u00e7\u00e3o intestinal, bem como infec\u00e7\u00f5es cr\u00f4nicas ou agudas e hipermetabolismo (aumento do gasto energ\u00e9tico e da necessidade cal\u00f3rica aumentada), comprometem negativamente o estado nutricional do idoso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cabe ainda lembrar que as mudan\u00e7as fisiol\u00f3gicas, pr\u00f3prias do envelhecimento, ocorrem principalmente nos sistemas: digest\u00f3rio, end\u00f3crino, imune, renal, nervoso, osteoarticular e cardiovascular, sendo que, dentre esses, as altera\u00e7\u00f5es do sistema digest\u00f3rio (relacionadas \u00e0 parte anat\u00f4mica, de motilidade e de fun\u00e7\u00e3o secretora) interferem diretamente no consumo alimentar, podendo tamb\u00e9m ser uma das causas da m\u00e1 nutri\u00e7\u00e3o em idosos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Salienta-se que nessa popula\u00e7\u00e3o h\u00e1 a diminui\u00e7\u00e3o natural dos bot\u00f5es gustativos (fornecem o sabor dos alimentos), o que tamb\u00e9m altera a percep\u00e7\u00e3o do paladar, podendo afetar a alimenta\u00e7\u00e3o. J\u00e1 dentre as modifica\u00e7\u00f5es ocorridas no est\u00f4mago durante o envelhecimento, a atrofia g\u00e1strica e a consequente diminui\u00e7\u00e3o da capacidade de secretar \u00e1cido g\u00e1strico (hipocloridria) s\u00e3o as mais comuns, ocasionando uma diminui\u00e7\u00e3o de absor\u00e7\u00e3o de diversos nutrientes. Vale ressaltar que esvaziamento g\u00e1strico se torna mais demorado, resultando em maior tempo de saciedade po\u0301s-prandial e menor sensac\u0327a\u0303o de fome pelo idoso, o que tambe\u0301m compromete a ingesta\u0303o alimentar, gerando a perda de peso.<\/span><\/p>\n<p><b>Hipocloridria: o que \u00e9 e quais os sintomas<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A hipocloridria pode ser definida como a diminui\u00e7\u00e3o da produ\u00e7\u00e3o de \u00e1cido clor\u00eddrico (HCl) no est\u00f4mago, o que faz com que o pH estomacal aumente, gerando o aparecimento de alguns sintomas, como:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">N\u00e1useas;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Distens\u00e3o abdominal;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Eructa\u00e7\u00e3o (arrotos);<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Diarreia;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">M\u00e1 absor\u00e7\u00e3o (presen\u00e7a de comida n\u00e3o digerida nas fezes);<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Gases;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Anemia ferropriva (por defici\u00eancia de ferro) ou megalobl\u00e1stica (defici\u00eancia de vitamina B12);<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Redu\u00e7\u00e3o do muco;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Defici\u00eancias nutricionais.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">As poss\u00edveis causas da hipocloridria na popula\u00e7\u00e3o idosa, est\u00e3o relacionadas \u00e0 gastrite cr\u00f4nica pelo uso frequente de anti\u00e1cidos ou medica\u00e7\u00f5es para refluxo gastro esof\u00e1gico, cirurgias no est\u00f4mago ou presen\u00e7a da <\/span><i><span style=\"font-weight: 400;\">Helicobacter pylori<\/span><\/i><span style=\"font-weight: 400;\">, um tipo de bact\u00e9ria mais relacionada a gastrites e \u00falceras p\u00e9pticas, cuja infec\u00e7\u00e3o \u00e9 muito comum e aumenta conforme a idade.<\/span><\/p>\n<p><b>Inibidores e anti\u00e1cidos: atua\u00e7\u00e3o perante a hipocloridria<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Os inibidores de Bomba de Pr\u00f3tons, mais conhecidos como lansoprazol, omeprazol, rabeprazol e pantoprazol, atuam na inibi\u00e7\u00e3o da produ\u00e7\u00e3o de \u00e1cido clor\u00eddrico, aumentando o pH g\u00e1strico, interferindo na absor\u00e7\u00e3o de todas as vitaminas e minerais. J\u00e1 os anti\u00e1cidos (sais de alum\u00ednio e magn\u00e9sio) atuam na redu\u00e7\u00e3o da absor\u00e7\u00e3o dos nutrientes ou aumentando a excre\u00e7\u00e3o urin\u00e1ria de alguns outros, como o c\u00e1lcio por exemplo. Dentre eles, os mais afetados quanto \u00e0 absor\u00e7\u00e3o, s\u00e3o:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; \u00c1cido F\u00f3lico (Vitamina B9)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; C\u00e1lcio<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Betacaroteno<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Cromo<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Ferro<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Zinco<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Vitamina C<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Vitamina B12 (Cobalamina)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuidado! Medicamentos inibidores de Bomba de Pr\u00f3tons, quando usados de forma cont\u00ednua, provocam um desafio funcional ao sistema gastrointestinal, que depende da produ\u00e7\u00e3o e presen\u00e7a natural do \u00e1cido clor\u00eddrico no est\u00f4mago para ionizar os micronutrientes e estes serem absorvidos pelo intestino.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A hipocloridria impede a absor\u00e7\u00e3o e a atividade de todos os micronutrientes. Al\u00e9m disso, a digest\u00e3o proteica e o combate a fungos e bact\u00e9rias ruins dependem de um pH \u00e1cido adequado no est\u00f4mago, sendo a hipocloridria respons\u00e1vel por s\u00e9rias consequ\u00eancias como disbiose intestinal (por destruir as bact\u00e9rias saud\u00e1veis) e o aumento de processos inflamat\u00f3rios devido \u00e0 dificuldade de digest\u00e3o e absor\u00e7\u00e3o de prote\u00edna. Neste cen\u00e1rio, o pH ideal para a absor\u00e7\u00e3o de micronutrientes ser\u00e1 alterado.<\/span><\/p>\n<p><b>Invista na nutri\u00e7\u00e3o adequada para evitar a hipocloridria<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Diante disso, \u00e9 necess\u00e1rio que a nutri\u00e7\u00e3o atue diretamente minimizando os sinais e sintomas ocasionados pela hipocloridria, como, por exemplo, se utilizando de:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Espinheira-santa: auxilia na preven\u00e7\u00e3o e tratamento da \u00falcera g\u00e1strica e duodenal e na esofagite de refluxo e h\u00e9rnia de hiato. Suas principais fun\u00e7\u00f5es s\u00e3o:<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\"> A\u00e7\u00e3o analg\u00e9sica, anti-inflamat\u00f3ria e antiulcerativa;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Protetora celular;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Antissecret\u00f3ria (semelhante ao omeprazol);<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Aumento da produ\u00e7\u00e3o de muco;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Protege do estresse causado por medicamentos.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Contra indicados em casos de:<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\"> C\u00e2ncer estrog\u00eanico-dependente;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Mulheres em tratamento para engravidar;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Gestantes e lactantes (redu\u00e7\u00e3o na produ\u00e7\u00e3o do leite materno);<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Hipersensibilidade.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">&#8211; Pimenta Chilli: a capsaicina \u00e9 um composto qu\u00edmico e o componente ativo das pimentas conhecidas internacionalmente como pimentas chilli, que possuem propriedades ben\u00e9ficas g\u00e1stricas. Suas principais fun\u00e7\u00f5es s\u00e3o:<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\"> Efeito antissecret\u00f3rio (previne a forma\u00e7\u00e3o de \u00falceras);<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Estimula a secre\u00e7\u00e3o de muco e secre\u00e7\u00e3o alcalina;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Anti-inflamat\u00f3rio;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Gastroprotetor.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">&#8211; Camomila: atua no trato gastrointestinal com as seguintes fun\u00e7\u00f5es:<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\"> Agindo em desordens gastrointestinais;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Melhorando a flatul\u00eancia, diarreia, espasmos, colite, gastrite e hemorr\u00f3idas;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> A\u00e7\u00e3o anti-inflamat\u00f3ria;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> A\u00e7\u00e3o antiespasm\u00f3dica (combate espasmos, contra\u00e7\u00f5es musculares esofagianas, por exemplo).<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">&#8211; Probi\u00f3ticos e Fibras Prebi\u00f3ticas: atuam em conjunto no combate \u00e0 disbiose, contribuindo para uma microbiota mais saud\u00e1vel e equilibrada.<\/span><\/p>\n<p><b>Conhe\u00e7a o hist\u00f3rico dos medicamentos utilizados pelo seu paciente<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Portanto, \u00e9 fundamental conhecer o hist\u00f3rico de medicamentos utilizados com maior frequ\u00eancia e os que ele est\u00e1 utilizando neste momento. Al\u00e9m de repor a microbiota saud\u00e1vel, \u00e9 necess\u00e1rio manter uma suplementa\u00e7\u00e3o dos micronutrientes quando indicado, associado a uma alimenta\u00e7\u00e3o saud\u00e1vel.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Refer\u00eancias Bibliogr\u00e1ficas:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">BORREGO, et. al. Causas da m\u00e1 nutri\u00e7\u00e3o, sarcopenia e fragilidade em idosos. Rev. Assoc. Bras. Nutr.: Vol.4, N.5, jan-jun 2012.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">CARREIRO, Denise Madi. Suplementa\u00e7\u00e3o Nutricional na pr\u00e1tica cl\u00ednica. 1\u00aa Edi\u00e7\u00e3o \u2013 S\u00e3o Paulo, SP, 2015.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">CONRADO, Bruna \u00c1fata et.al. Disbiose Intestinal em idosos e aplicabilidade dos probi\u00f3ticos e prebi\u00f3ticos. Caderno Unifoa. Volta Redonda, n.36. p. 71-78. Abr. 2018.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">LIMA, Lhma et al. Auto-percep\u00e7\u00e3o oral e sele\u00e7\u00e3o de alimentos por idosos usu\u00e1rios de pr\u00f3teses totais. Rev. Fac. Odontol. Araraquara. 2007; 36(2): 131-136.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">TS, Roberto; FC, Bana. Mudan\u00e7as fisiol\u00f3gicas do sistema digest\u00f3rio na terceira idade. In: Magnoni D, Cukier C, Oliveira PA (Org.). Nutri\u00e7\u00e3o na terceira idade. S\u00e3o Paulo: Sarvier, 2010.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saiba o que \u00e9 hipocloridria, seus sintomas e como evitar o seu surgimento atrav\u00e9s de uma boa nutri\u00e7\u00e3o na terceira idade.<\/p>\n","protected":false},"author":3,"featured_media":800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[47],"tags":[63,64],"class_list":["post-799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo","tag-solucoes-para-home-care","tag-terceira-idade"],"acf":[],"_links":{"self":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/comments?post=799"}],"version-history":[{"count":0,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/media?parent=799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/categories?post=799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/tags?post=799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}