{"id":1746,"date":"2022-04-04T10:05:10","date_gmt":"2022-04-04T13:05:10","guid":{"rendered":"https:\/\/institucional.nutrirsaudestore.com.br\/?p=1029"},"modified":"2022-04-04T10:05:10","modified_gmt":"2022-04-04T13:05:10","slug":"curcuma-conheca-o-poder-dessa-planta-para-a-saude","status":"publish","type":"post","link":"https:\/\/nutrirsaudestore.com.br\/institucional\/curcuma-conheca-o-poder-dessa-planta-para-a-saude\/","title":{"rendered":"C\u00farcuma: conhe\u00e7a o poder dessa planta para a sa\u00fade"},"content":{"rendered":"<p><i><span style=\"font-weight: 400;\">Por Eduarda Lages<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Considerada uma preciosa especiaria, a c\u00farcuma vem ganhando cada vez mais espa\u00e7o no mundo da suplementa\u00e7\u00e3o, por possuir efeitos antioxidantes e antimicrobianos, agindo em v\u00e1rios aspectos da sa\u00fade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conhecida tamb\u00e9m por a\u00e7afr\u00e3o-da-terra, \u00e9 utilizada por muitas pessoas em v\u00e1rias prepara\u00e7\u00f5es regionais, por possuir colora\u00e7\u00e3o alaranjada intensa e aroma e sabor caracter\u00edstico. Atualmente, tamb\u00e9m \u00e9 poss\u00edvel encontr\u00e1-la em suplementos alimentares, para complementar a nutri\u00e7\u00e3o e usufruir de suas qualidades.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Siga a leitura e fique por dentro de todas as vantagens que a c\u00farcuma pode oferecer \u00e0 sua sa\u00fade!\u00a0<\/span><\/p>\n<p><b>Quais s\u00e3o os benef\u00edcios de consumir a c\u00farcuma?\u00a0<\/b><b><\/b><\/p>\n<p><b>\u00a0 \u00a0 \u00a0&#8211; \u00c9 anti-inflamat\u00f3ria<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Seu princ\u00edpio ativo \u00e9 a curcumina, que atua inibindo enzimas anti-inflamat\u00f3rias, reparando os danos celulares e combatendo agentes invasores.\u00a0<\/span><b><\/b><\/p>\n<p><b>\u00a0 \u00a0 \u00a0&#8211; Cuida da sa\u00fade do c\u00e9rebro<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Segundo um estudo da Universidade da Calif\u00f3rnia, realizado em 2014, o consumo da curcumina diminui as chances de desenvolver Alzheimer, esclerose m\u00faltipla, Parkinson e depress\u00e3o. No mesmo ano, outras duas institui\u00e7\u00f5es fizeram pesquisas que constataram a diminui\u00e7\u00e3o do risco de degenera\u00e7\u00e3o cerebral, decorrente da ingest\u00e3o da subst\u00e2ncia, auxiliando no tratamento das doen\u00e7as neurodegenerativas e melhorando o crescimento das c\u00e9lulas-tronco.\u00a0<\/span><b><\/b><\/p>\n<p><b>\u00a0 \u00a0 \u00a0&#8211; Aliada de tratamentos oncol\u00f3gicos<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A Universidade Federal de Goi\u00e1s (UFG) realizou um estudo sobre a c\u00farcuma no tratamento de um tipo de melanoma, um dos mais severos c\u00e2nceres de pele, tendo resultados positivos contra as\u00a0 prote\u00ednas das c\u00e9lulas cancerosas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Outra pesquisa, da Universidade Federal do Rio Grande do Sul (UFRGS), analisou o uso da curcumina em cobaias com com c\u00e2ncer cerebral, constatando uma diminui\u00e7\u00e3o significativa do tumor, atuando contra uma prote\u00edna nas c\u00e9lulas de glioblastomas.\u00a0<\/span><b><\/b><\/p>\n<p><b>\u00a0 \u00a0 \u00a0&#8211; Alivia os sintomas da artrite e da artrose<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A planta se mostra efetiva contra os efeitos dessas doen\u00e7as, que afetam grande parte da popula\u00e7\u00e3o idosa. Isso porque o consumo di\u00e1rio do ingrediente combate os radicais livres, diminuindo as inflama\u00e7\u00f5es nas articula\u00e7\u00f5es.\u00a0<\/span><\/p>\n<p><b>Confira uma receita pr\u00e1tica com c\u00farcuma<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Veja como fazer o leite dourado, uma bebida indiana muito consumida por ser um potente antioxidante. Simples de fazer, ideal para o dia a dia.\u00a0\u00a0<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-1030 aligncenter\" src=\"http:\/\/institucional.nutrirsaudestore.com.br\/wp-content\/uploads\/2022\/04\/image1-300x200.png\" alt=\"\" width=\"470\" height=\"313\" \/><\/p>\n<p><b>Ingredientes<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0 \u00a0 \u00a0&#8211; 1 colher (sopa) de mel<br \/>\n<\/span><span style=\"font-weight: 400;\">\u00a0 \u00a0 \u00a0&#8211; 1 colher (ch\u00e1) de c\u00farcuma em p\u00f3<br \/>\n<\/span><span style=\"font-weight: 400;\">\u00a0 \u00a0 \u00a0&#8211; 1\/4 colher (ch\u00e1) de gengibre em p\u00f3<br \/>\n<\/span><span style=\"font-weight: 400;\">\u00a0 \u00a0 \u00a0&#8211; 1\/4 colher (ch\u00e1) de cardamomo em p\u00f3<br \/>\n<\/span><span style=\"font-weight: 400;\">\u00a0 \u00a0 \u00a0&#8211; 1\/4 colher (ch\u00e1) de canela em p\u00f3<br \/>\n<\/span><span style=\"font-weight: 400;\">\u00a0 \u00a0 \u00a0&#8211; 2 colheres (sopa) de \u00e1gua fervente<br \/>\n<\/span><span style=\"font-weight: 400;\">\u00a0 \u00a0 \u00a0&#8211; 2 colheres (sopa) de leite de coco ou de am\u00eandoas<\/span><\/p>\n<p><b>Modo de preparo<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Em uma tigela m\u00e9dia, misture o mel, a c\u00farcuma, o gengibre, o cardamomo e a canela. Em seguida, acrescente a \u00e1gua fervente e mexa bem para dissolver tudo. Junte o leite, misture e sirva.<\/span><\/p>\n<p><b>Encontre a c\u00farcuma na Nutrir Sa\u00fade<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Aqui, na Nutrir Sa\u00fade, disponibilizamos esse potente ativo em forma de c\u00e1psulas, para trazer cada vez mais benef\u00edcios para a sua sa\u00fade. Assim, al\u00e9m de consumi-lo como tempero nas refei\u00e7\u00f5es, \u00e9 poss\u00edvel us\u00e1-lo como suplementa\u00e7\u00e3o.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><em><strong><a href=\"https:\/\/api.whatsapp.com\/send?phone=558440089992&amp;text=Ol%C3%A1,%20tudo%20bem%3F%20Venho%20atrav%C3%A9s%20de%20um%20e-mail%20que%20recebi%20de%20voc%C3%AAs%20e%20gostaria%20de%20uma%20informa%C3%A7%C3%A3o,%20por%20favor.\" target=\"_blank\" rel=\"noopener\">Clique aqui<\/a><\/strong><\/em> e solicite a sua c\u00farcuma!<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O consumo da c\u00farcuma, tamb\u00e9m conhecida como a\u00e7afr\u00e3o-da-terra, garante in\u00fameros benef\u00edcios \u00e0 sa\u00fade. Descubra os principais e confira uma dica de receita! <\/p>\n","protected":false},"author":3,"featured_media":1031,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[103],"class_list":["post-1746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-curcuma"],"acf":[],"_links":{"self":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/comments?post=1746"}],"version-history":[{"count":0,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/media?parent=1746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/categories?post=1746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/tags?post=1746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}