{"id":1738,"date":"2022-02-04T11:20:17","date_gmt":"2022-02-04T14:20:17","guid":{"rendered":"https:\/\/institucional.nutrirsaudestore.com.br\/?p=955"},"modified":"2022-02-04T11:20:17","modified_gmt":"2022-02-04T14:20:17","slug":"cuidados-no-verao-aproveite-a-estacao-com-saude","status":"publish","type":"post","link":"https:\/\/nutrirsaudestore.com.br\/institucional\/cuidados-no-verao-aproveite-a-estacao-com-saude\/","title":{"rendered":"Cuidados no ver\u00e3o: aproveite a esta\u00e7\u00e3o com sa\u00fade"},"content":{"rendered":"<p><b>Por Eduarda Lages<\/b><\/p>\n<p><span style=\"font-weight: 400;\">O ver\u00e3o est\u00e1 a\u00ed. \u00c9 tempo de aproveitar as f\u00e9rias, curtir a praia e mergulhar na piscina, pegar um sol para bronzear e comer as del\u00edcias da esta\u00e7\u00e3o, como o sorvete.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, \u00e9 preciso estar atento: a temperatura mais elevada pode trazer riscos \u00e0 sa\u00fade em rela\u00e7\u00e3o \u00e0 hidrata\u00e7\u00e3o e alimenta\u00e7\u00e3o.\u00a0 Afinal, \u00e9 justamente nesta \u00e9poca do ano que o nosso corpo fica mais prop\u00edcio ao risco de intoxica\u00e7\u00e3o alimentar e \u00e0 desidrata\u00e7\u00e3o.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Confira quais cuidados tomar e por que \u00e9 importante estar 100% saud\u00e1vel neste per\u00edodo!<\/span><\/p>\n<p><b>Intoxica\u00e7\u00e3o alimentar: tenha cuidado!<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A intoxica\u00e7\u00e3o alimentar ocorre por meio do consumo de alimentos mal armazenados que, consequentemente, ficam estragados ou n\u00e3o s\u00e3o cozidos na temperatura ideal e nem limpos de maneira correta, causando desconfortos intestinais, infec\u00e7\u00f5es, diarreia e v\u00f4mitos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Especialmente nos dias de calor, a tend\u00eancia de prolifera\u00e7\u00e3o de bact\u00e9rias e microorganismos nos alimentos acontece de forma r\u00e1pida, por conta da temperatura elevada, por isso, \u00e9 necess\u00e1rio que os cuidados sejam redobrados para que voc\u00ea n\u00e3o consuma alimentos contaminados, trazendo assim risco para a sua sa\u00fade.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por n\u00e3o sabermos como os alimentos consumidos fora de casa foram armazenados e preparados, podemos acabar nos contaminando sem saber, por isso, \u00e9 preciso ficar atento ao sabor, odor do alimento e textura.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Agora, veja algumas dicas para evitar a intoxica\u00e7\u00e3o alimentar:\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0 \u00a0 &#8211;\u00a0 Evite consumir alimentos dos quais voc\u00ea n\u00e3o sabe a proced\u00eancia, para evitar problemas gastrointestinais.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0 \u00a0 &#8211;\u00a0 Quando for \u00e0 praia, evite consumir sempre alimentos n\u00e3o t\u00e3o saud\u00e1veis, como frituras, doces e bebidas alco\u00f3licas. Substitua por aqueles saud\u00e1veis como: \u00e1gua de coco, ch\u00e1 gelado, frutas, picol\u00e9s de frutas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0 \u00a0 &#8211;\u00a0 Sempre que poss\u00edvel, prepare sua pr\u00f3pria comida e a armazene em um cooler, buscando sempre os alimentos in natura ou minimamente processados.<\/span><\/p>\n<p><b>A hidrata\u00e7\u00e3o tamb\u00e9m merece aten\u00e7\u00e3o<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Quanto \u00e0 hidrata\u00e7\u00e3o, \u00e9 de suma import\u00e2ncia que ela esteja 100%, pois precisamos repor tudo o que foi perdido com o suor por conta do calor. Neste caso, \u00e9 fundamental se manter hidratado, consumindo no m\u00ednimo 2 litros de \u00e1gua por dia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Caso voc\u00ea tenha dificuldade de consumir \u00e1gua, procure reinventar o l\u00edquido, adicionando frutas para deix\u00e1-lo saborizado. Isso combina muito com o ver\u00e3o, al\u00e9m de proporcionar um drink lindo e nutritivo.\u00a0<\/span><\/p>\n<p><b>Conte com a Nutrir!<\/b><\/p>\n<p><span style=\"font-weight: 400;\">E a dica que n\u00e3o pode faltar: se divirta com a sua fam\u00edlia e lembre-se que na Nutrir Sa\u00fade tamb\u00e9m existem op\u00e7\u00f5es de bebidas para o ver\u00e3o que s\u00e3o sucesso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/api.whatsapp.com\/send?phone=558440089992\" target=\"_blank\" rel=\"noopener\">Clique aqui<\/a> e saiba mais!\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A conscientiza\u00e7\u00e3o sobre os cuidados que as pessoas devem ter nos tempos de ver\u00e3o com o aumento da temperatura e com a alimenta\u00e7\u00e3o \u00e9 essencial. Saiba Mais!<\/p>\n","protected":false},"author":3,"featured_media":956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[47],"tags":[95,73],"class_list":["post-1738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo","tag-dicas","tag-saude"],"acf":[],"_links":{"self":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/comments?post=1738"}],"version-history":[{"count":0,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/media\/956"}],"wp:attachment":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/media?parent=1738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/categories?post=1738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/tags?post=1738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}