{"id":1726,"date":"2021-10-22T08:56:53","date_gmt":"2021-10-22T11:56:53","guid":{"rendered":"https:\/\/institucional.nutrirsaudestore.com.br\/?p=841"},"modified":"2021-10-22T08:56:53","modified_gmt":"2021-10-22T11:56:53","slug":"quais-sao-as-vitaminas-essenciais-para-um-corpo-saudavel","status":"publish","type":"post","link":"https:\/\/nutrirsaudestore.com.br\/institucional\/quais-sao-as-vitaminas-essenciais-para-um-corpo-saudavel\/","title":{"rendered":"Quais s\u00e3o as vitaminas essenciais para um corpo saud\u00e1vel?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">A alimenta\u00e7\u00e3o equilibrada \u00e9 essencial para conquistar um corpo saud\u00e1vel. Mas, al\u00e9m de apostar em alimentos in natura, ricos em fibras e integrais, \u00e9 necess\u00e1rio estar atento \u00e0s vitaminas que eles proporcionam para ter sa\u00fade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A maioria das pessoas n\u00e3o conseguem ingerir a dosagem correta das vitaminas essenciais para o organismo, principalmente com o alto consumo dos alimentos ultraprocessados, o famoso &#8220;fast food&#8221;, por isso, a import\u00e2ncia da suplementa\u00e7\u00e3o de certas vitaminas para que n\u00e3o ocorra defici\u00eancia delas e gere problemas de sa\u00fade como iremos relatar a seguir.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vamos falar um pouco mais sobre as vitaminas fundamentais para o corpo e suas finalidades, bem como, quais suplementos s\u00e3o ideais para fazer a reposi\u00e7\u00e3o, quando necess\u00e1rio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Continue aqui e boa leitura!<\/span><\/p>\n<p><b>As vitaminas essenciais para um corpo saud\u00e1vel e suas fun\u00e7\u00f5es<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Confira as principais vitaminas para manter um corpo saud\u00e1vel e quais as consequ\u00eancias de sua aus\u00eancia:<\/span><\/p>\n<p><b>Vitamina A<\/b><span style=\"font-weight: 400;\">: auxilia no processo de crescimento dos tecidos, no sistema imunol\u00f3gico e na integridade da vis\u00e3o. A car\u00eancia do nutriente, entretanto, provoca altera\u00e7\u00f5es na qualidade dos olhos e infec\u00e7\u00f5es frequentes.<\/span><\/p>\n<p><b>Vitaminas do complexo B: <\/b><span style=\"font-weight: 400;\">respons\u00e1veis pelo aumento da circula\u00e7\u00e3o e aux\u00edlio na forma\u00e7\u00e3o do sangue, aumentando, inclusive, a atividade mental e a fun\u00e7\u00e3o cerebral. A falta dessas vitaminas provoca cansa\u00e7o, dores de cabe\u00e7a, n\u00e1useas e depress\u00e3o.<\/span><\/p>\n<p><b>Vitamina C: <\/b><span style=\"font-weight: 400;\">antioxidante, ela favorece a cicatriza\u00e7\u00e3o de feridas e auxilia na absor\u00e7\u00e3o do ferro, al\u00e9m de ser essencial para o sistema imunol\u00f3gico. A sua car\u00eancia \u00e9 respons\u00e1vel pelo surgimento de resfriados, anemia, varizes e problemas de cicatriza\u00e7\u00e3o.<\/span><\/p>\n<p><b>Vitamina D:<\/b><span style=\"font-weight: 400;\"> fun\u00e7\u00e3o ativa no metabolismo do c\u00e1lcio, na forma\u00e7\u00e3o \u00f3ssea e no fortalecimento do sistema imunol\u00f3gico. Sua defici\u00eancia est\u00e1 ligada a v\u00e1rias doen\u00e7as autoimunes, como diabetes melito insulinodependente, l\u00fapus eritematoso sist\u00eamico, esclerose m\u00faltipla, entre outras.<\/span><\/p>\n<p><b>Vitamina E: <\/b><span style=\"font-weight: 400;\">a\u00e7\u00e3o antioxidante, reduzindo o processo de envelhecimento das c\u00e9lulas e da pele. A subst\u00e2ncia aumenta o sistema imune e ajuda na prote\u00e7\u00e3o contra doen\u00e7as cr\u00f4nicas. Sua aus\u00eancia pode provocar queda de cabelo, taquicardia, cansa\u00e7o e dificuldade de cicatriza\u00e7\u00e3o.<\/span><\/p>\n<p><b>A suplementa\u00e7\u00e3o pode completar as vitaminas<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Entenda por que nem sempre \u00e9 poss\u00edvel repor somente com alimenta\u00e7\u00e3o. Mas, vale salientar que \u00e9 primordial uma consulta antes da suplementa\u00e7\u00e3o, para que um profissional especializado possa indicar a dosagem correta para o seu organismo.\u00a0<\/span><\/p>\n<p><b>&#8211; Vitamina A<\/b><\/p>\n<p><span style=\"font-weight: 400;\">H\u00e1 certa dificuldade entre as pessoas em conseguir rep\u00f4-la por meio da alimenta\u00e7\u00e3o (alimentos como ab\u00f3bora, batata-doce, cenoura, manga, mostarda, couve e espinafre s\u00e3o ricos neste nutriente), porque a absor\u00e7\u00e3o \u00e9 muito pequena.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 importante salientar aqui tamb\u00e9m sobre a vacina\u00e7\u00e3o de vitamina A em crian\u00e7as. Pesquisas apontam que, por meio da realiza\u00e7\u00e3o da vacina, houve uma redu\u00e7\u00e3o do risco global de morte em 24%, de mortalidade por diarreia em 28% e de mortalidade por todas as causas, em crian\u00e7as HIV positivo, em 45%.<\/span><\/p>\n<p><b>&#8211; Complexo B (B12)<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A suplementa\u00e7\u00e3o dessa vitamina deve ser primordial nas pessoas que s\u00e3o adeptas ao veganismo e n\u00e3o consomem alguns dos alimentos que s\u00e3o ricos na vitamina B12, (podendo ser encontrado na gema de ovo, no arroz, em peixes, legumes, no f\u00edgado, na p\u00eara, na carne de porco, no germe de trigo e nos gr\u00e3os). \u00c9 essencial fazer essa suplementa\u00e7\u00e3o para que o seu corpo n\u00e3o deixe de ser nutrido com essa vitamina e possa acarretar alguns problemas de sa\u00fade.\u00a0<\/span><\/p>\n<p><b>&#8211; Vitamina C<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Encontrada em frutas c\u00edtricas como acerola, laranja, goiaba, abacaxi e caju. Como as frutas est\u00e3o cada vez mais pobres em nutrientes, dificilmente se consegue a dose ideal ao ingeri-las. Em momentos de baixa imunidade e resfriado, a dose pode at\u00e9 aumentar.<\/span><\/p>\n<p><b>&#8211; Vitamina D<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A melhor forma de suplementa\u00e7\u00e3o \u00e9 a vitamina D no formato D3 (colecalciferol), absorvida com mais facilidade que a D2 (ergosterol), que pode ser encontrada em <\/span><span style=\"font-weight: 400;\">f\u00edgado, sardinha, gema de ovo, atum e cogumelos.\u00a0<\/span><\/p>\n<p><b>&#8211; Vitamina E<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A vitamina E tamb\u00e9m \u00e9 um nutriente dif\u00edcil de se obter somente atrav\u00e9s da dieta. A vitamina \u00e9 encontrada em \u00f3leos vegetais, como \u00f3leo de girassol, oleaginosas (nozes, am\u00eandoas, castanhas), folhas verdes escuras, g\u00e9rmen de trigo e gema do ovo.<\/span><\/p>\n<p><b>Tenha uma vida mais saud\u00e1vel<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A Nutrir Sa\u00fade oferece diversos suplementos nutricionais para auxiliar na sua sa\u00fade, tornando o seu corpo mais saud\u00e1vel.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fale com as nossas nutris e entenda as necessidades nutricionais do seu corpo para garantir os suplementos ideais para voc\u00ea. Clique <a href=\"https:\/\/api.whatsapp.com\/send?phone=558440089992&amp;text=Ol%C3%A1,%20tudo%20bem%3F%20Venho%20atrav%C3%A9s%20de%20um%20e-mail%20que%20recebi%20de%20voc%C3%AAs%20e%20gostaria%20de%20uma%20informa%C3%A7%C3%A3o,%20por%20favor.\" target=\"_blank\" rel=\"noopener\"><strong>aqui.<\/strong><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saiba quais s\u00e3o as principais vitaminas a serem ingeridas para garantir um corpo saud\u00e1vel. <\/p>\n","protected":false},"author":3,"featured_media":842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[47],"tags":[82],"class_list":["post-1726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo","tag-vitaminas"],"acf":[],"_links":{"self":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/comments?post=1726"}],"version-history":[{"count":0,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/media?parent=1726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/categories?post=1726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/tags?post=1726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}