{"id":1724,"date":"2021-10-08T10:17:35","date_gmt":"2021-10-08T13:17:35","guid":{"rendered":"https:\/\/institucional.nutrirsaudestore.com.br\/?p=828"},"modified":"2021-10-08T10:17:35","modified_gmt":"2021-10-08T13:17:35","slug":"introducao-precoce-de-acucar-na-infancia-saiba-por-que-e-prejudicial-a-saude","status":"publish","type":"post","link":"https:\/\/nutrirsaudestore.com.br\/institucional\/introducao-precoce-de-acucar-na-infancia-saiba-por-que-e-prejudicial-a-saude\/","title":{"rendered":"Introdu\u00e7\u00e3o precoce de a\u00e7\u00facar na inf\u00e2ncia: saiba por que \u00e9 prejudicial \u00e0 sa\u00fade"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Por: Luana Lacet<\/span><\/p>\n<p><em><strong>\u201cMas \u00e9 s\u00f3 um docinho\u201d. Se voc\u00ea \u00e9 m\u00e3e, pai ou convive com crian\u00e7as, com certeza j\u00e1 ouviu essa frase, n\u00e3o \u00e9 mesmo?<\/strong><\/em><\/p>\n<p><span style=\"font-weight: 400;\">Isso \u00e9 natural, j\u00e1 que, para o adulto, \u00e9 muito dif\u00edcil resistir \u00e0 tenta\u00e7\u00e3o de oferecer guloseimas para as crian\u00e7as. No entanto, estudos relatam que o excesso de consumo de a\u00e7\u00facar na inf\u00e2ncia pode ser bastante prejudicial \u00e0 sa\u00fade e desenvolvimento dos pequenos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hoje, vamos abordar a introdu\u00e7\u00e3o de a\u00e7\u00facar precoce na inf\u00e2ncia. Continue aqui e entenda mais sobre este assunto.<\/span><\/p>\n<p><b>O a\u00e7\u00facar na inf\u00e2ncia\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">O a\u00e7\u00facar na inf\u00e2ncia \u00e9 mal\u00e9fico porque est\u00e1 associado \u00e0 hiperatividade, dificuldade de concentra\u00e7\u00e3o, irritabilidade e outros problemas psicol\u00f3gicos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ele tamb\u00e9m ocasiona uma diminui\u00e7\u00e3o de antioxidantes, como glutationa e catalase, o que leva a um aumento do estresse oxidativo e influencia a imunidade e o metabolismo. Al\u00e9m disso, tamb\u00e9m afeta a qualidade e dura\u00e7\u00e3o do sono, podendo alterar a produ\u00e7\u00e3o do horm\u00f4nio do crescimento, mecanismos metab\u00f3licos e rea\u00e7\u00f5es enzim\u00e1ticas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ainda, como consequ\u00eancia, o a\u00e7\u00facar pode desencadear alergias, intoler\u00e2ncias alimentares e doen\u00e7as intestinais.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre os poss\u00edveis efeitos neurais do consumo de a\u00e7\u00facar na inf\u00e2ncia est\u00e3o preju\u00edzos ao desenvolvimento da mem\u00f3ria e da coordena\u00e7\u00e3o motora, redu\u00e7\u00e3o do antioxidante glutationa e aumento do n\u00edvel de malondialde\u00eddo (MDA) no c\u00e9rebro. Este \u00faltimo contribui para o desenvolvimento do transtorno do d\u00e9ficit de aten\u00e7\u00e3o com hiperatividade (TDAH).<\/span><\/p>\n<p><b>\u201cMas \u00e9 s\u00f3 um docinho!\u201d<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea \u00e9 m\u00e3e ou pai e j\u00e1 tentou preservar seu filho desta introdu\u00e7\u00e3o precoce, possivelmente j\u00e1 escutou in\u00fameros palpites que costumam ser dados por familiares, amigos, vizinhos e, \u00e0s vezes, at\u00e9 por desconhecidos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, ao mesmo tempo, se recusou essa oferta e se manteve o seu pequeno longe do consumo de itens ado\u00e7ados, est\u00e1 seguindo os passos certos para cuidar da sa\u00fade dele.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Principalmente nos dois primeiros anos de vida, as frutas e bebidas oferecidas \u00e0s crian\u00e7as n\u00e3o devem ser ado\u00e7adas com nenhum tipo de a\u00e7\u00facar: branco, mascavo, cristal, demerara, a\u00e7\u00facar de coco, xarope de milho, mel, melado ou rapadura. Inclusive, deve-se ter aten\u00e7\u00e3o \u00e0s prepara\u00e7\u00f5es dentro e fora do lar, consumidas pelas crian\u00e7as, que podem conter a\u00e7\u00facar, como bolos, biscoitos, doces e geleias.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O a\u00e7\u00facar est\u00e1 sempre presente, basta ter aten\u00e7\u00e3o em r\u00f3tulos de produtos processados. Seu sabor \u00e9 associado ao prazer instant\u00e2neo, j\u00e1 que a <\/span><span style=\"font-weight: 400;\">recompensa neuronal pelo consumo de a\u00e7\u00facar se d\u00e1 pela r\u00e1pida libera\u00e7\u00e3o de dopamina. No entanto,<\/span><span style=\"font-weight: 400;\"> cada vez mais, a ci\u00eancia o coloca no alvo dos preju\u00edzos \u00e0 sa\u00fade.\u00a0<\/span><\/p>\n<p><b>Crian\u00e7as n\u00e3o devem consumir a\u00e7\u00facar antes dos dois anos<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Estudos mostram que a ingest\u00e3o de doces antes dessa idade eleva o risco de obesidade tanto na inf\u00e2ncia, quanto na adolesc\u00eancia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando comemos doce, nosso metabolismo eleva os n\u00edveis de glicose e estimula o p\u00e2ncreas a produzir e liberar um horm\u00f4nio chamado insulina, que, por sua vez, vai transformar essa glicose em energia. Por consequ\u00eancia, a energia se torna estoque de gordura, que leva ao aumento de peso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De acordo com as novas diretrizes, pessoas com idade entre 2 e 18 anos n\u00e3o devem comer nem beber mais do que 25 gramas de a\u00e7\u00facar por dia &#8211; o equivalente a 6 colheres de ch\u00e1.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 beb\u00eas e crian\u00e7as n\u00e3o devem ter contato com o a\u00e7\u00facar, especialmente nos primeiros dois anos de vida! Est\u00e1 mais que comprovado cientificamente que os primeiros mil dias de vida s\u00e3o cruciais para a sa\u00fade do indiv\u00edduo com repercuss\u00f5es por <\/span><b>TODA A VIDA!<\/b><\/p>\n<p><b>Opte por alimentos sem a\u00e7\u00facar<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Na Nutrir Sa\u00fade, voc\u00ea encontra alimentos e suplementos para crian\u00e7as sem a\u00e7\u00facar, al\u00e9m de fornecer micro e macronutrientes que promovem a sa\u00fade. Confira algumas sugest\u00f5es:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Gomas vitam\u00ednicas infantis sem a\u00e7\u00facar, corantes artificiais ou ado\u00e7antes artificiais;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Multivitam\u00ednico na forma de suco em p\u00f3 sem a\u00e7\u00facar, para preparo com \u00e1gua ou uso em receitas;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Multivitam\u00ednicos sem a\u00e7\u00facar, para preparo com leite ou como ingredientes de receitas;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Op\u00e7\u00f5es para substitui\u00e7\u00e3o de achocolatados e similares.<\/span><\/p>\n<p><b>Fale com a Nutrir<\/b><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Temos um time de nutricionistas que pode ajudar voc\u00ea a suprir suas necessidades alimentares e de nutrientes, indicando as melhores pr\u00e1ticas e uma dieta adequada para todas as fases da vida.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Clique <strong><a href=\"https:\/\/api.whatsapp.com\/send?phone=558440089992&amp;text=Ol%C3%A1,%20tudo%20bem%3F%20Venho%20atrav%C3%A9s%20de%20um%20e-mail%20que%20recebi%20de%20voc%C3%AAs%20e%20gostaria%20de%20uma%20informa%C3%A7%C3%A3o,%20por%20favor.\" target=\"_blank\" rel=\"noopener\">aqui<\/a><\/strong> e entre em contato conosco para saber mais!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cMas \u00e9 s\u00f3 um docinho\u201d: entenda por que crian\u00e7as at\u00e9 os 2 anos de idade n\u00e3o devem consumir a\u00e7\u00facar.<\/p>\n","protected":false},"author":3,"featured_media":829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[47],"tags":[80,81,58],"class_list":["post-1724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo","tag-acucar","tag-crianca","tag-nutricao-clinica-e-terapeutica"],"acf":[],"_links":{"self":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/comments?post=1724"}],"version-history":[{"count":0,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/media\/829"}],"wp:attachment":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/media?parent=1724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/categories?post=1724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/tags?post=1724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}