{"id":1714,"date":"2021-06-18T11:59:29","date_gmt":"2021-06-18T14:59:29","guid":{"rendered":"https:\/\/institucional.nutrirsaudestore.com.br\/?p=696"},"modified":"2021-06-18T11:59:29","modified_gmt":"2021-06-18T14:59:29","slug":"dieta-enteral-artesanal-ou-industrializada-entenda-a-diferenca","status":"publish","type":"post","link":"https:\/\/nutrirsaudestore.com.br\/institucional\/dieta-enteral-artesanal-ou-industrializada-entenda-a-diferenca\/","title":{"rendered":"Dieta enteral artesanal ou industrializada: entenda a diferen\u00e7a"},"content":{"rendered":"<p>Por: Roseane Nabas<\/p>\n<p><span style=\"font-weight: 400;\">A Terapia Nutricional Enteral (TNE) \u00e9 importante para recupera\u00e7\u00e3o e\/ou manuten\u00e7\u00e3o do estado nutricional do paciente. Ela auxilia na melhora dos resultados cl\u00ednicos, aumento da imunidade, diminui\u00e7\u00e3o do estresse fisiol\u00f3gico, tempo de interna\u00e7\u00e3o e os gastos hospitalares.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 indicada para pacientes que n\u00e3o t\u00eam condi\u00e7\u00f5es de se alimentar totalmente ou parcialmente por via oral, mas que apresentam o trato gastrintestinal funcionante, podendo ser administrada atrav\u00e9s da nutri\u00e7\u00e3o enteral industrializada ou caseira.<\/span><\/p>\n<p><b>Dietas industrializadas, artesanais ou caseiras?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">As dietas n\u00e3o industrializadas, artesanais ou caseiras consistem em uma f\u00f3rmula manipulada a partir de alimentos in natura cozidos, liquidificados e coados (arroz, \u00f3leo vegetal, leite, ovo, caldo de carne, farinhas, por exemplo).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ela deve ser prescrita por um profissional da sa\u00fade capacitado, que dever\u00e1 determinar corretamente a combina\u00e7\u00e3o desses alimentos de modo que sua composi\u00e7\u00e3o seja completa e equilibrada do ponto de vista nutricional e adequada \u00e0 condi\u00e7\u00e3o cl\u00ednica do paciente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, muitas vezes a dieta caseira n\u00e3o \u00e9 capaz de atingir as metas nutricionais do paciente, sendo necess\u00e1rio a utiliza\u00e7\u00e3o de algum complemento alimentar industrializado como forma de agregar nutrientes \u00e0 prepara\u00e7\u00e3o (maltodextrina, albumina, vitaminas e minerais, por exemplo).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A RDC n\u00b0 63\/2000 (ANVISA) estabelece os requisitos m\u00ednimos exigidos para a TNE no Brasil, objetivando garantir maior seguran\u00e7a e qualidade nutricional em sua utiliza\u00e7\u00e3o. Com isso, o uso da dieta enteral artesanal vem, ao longo dos anos, perdendo mercado para a dieta industrializada. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por\u00e9m, ainda existe a concep\u00e7\u00e3o de que as dietas artesanais s\u00e3o mais adequadas e de menor custo que as f\u00f3rmulas enterais industrializadas, principalmente quando se trata de pacientes em aten\u00e7\u00e3o domiciliar.<\/span><\/p>\n<p><b>Entenda sobre a dieta enteral industrializada<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A nutri\u00e7\u00e3o enteral industrializada pode ser classificada em sistema aberto e sistema fechado. No sistema aberto, os nutrientes industrializados podem se apresentar na forma de p\u00f3 ou l\u00edquido e precisam ser manipulados, dosados e envasados de acordo com a prescri\u00e7\u00e3o diet\u00e9tica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 o sistema fechado \u00e9 constitu\u00eddo por nutrientes e volumes padronizados, apresentado em embalagem est\u00e9ril, hermeticamente fechada, pronta para ser administrada sem nenhum tipo de contato com ar ambiente ou manipulador. Sendo assim, o sistema aberto apresenta um menor custo, uma vez que n\u00e3o s\u00e3o considerados custos com os profissionais manipuladores, insumos, \u00e1rea f\u00edsica e equipamentos.<\/span><\/p>\n<p><b>Saiba mais sobre a dieta enteral artesanal<\/b><\/p>\n<p><span style=\"font-weight: 400;\">As dietas enterais artesanais exigem um controle r\u00edgido das condi\u00e7\u00f5es higi\u00eanicas no preparo, acondicionamento e administra\u00e7\u00e3o dos alimentos, estando sujeitas a um maior risco de contamina\u00e7\u00e3o microbiol\u00f3gica, uma vez que os alimentos utilizados para suas prepara\u00e7\u00f5es apresentam um pH ligeiramente \u00e1cido ou neutro, possibilitando o crescimento de bact\u00e9rias e contribuindo para um risco maior de contamina\u00e7\u00e3o em virtude da pr\u00f3pria manipula\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, a falta de padroniza\u00e7\u00e3o dos procedimentos, da quantidade dos ingredientes e do tempo de coc\u00e7\u00e3o podem tornar a composi\u00e7\u00e3o nutricional do produto final vari\u00e1vel, tornando dif\u00edcil a obten\u00e7\u00e3o da densidade cal\u00f3rica, proteica e distribui\u00e7\u00e3o de macro e micronutrientes adequadas de acordo com as necessidades do paciente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante o processamento das f\u00f3rmulas ocorrem grandes perdas de nutrientes. Estudos demonstram que em dietas enterais artesanais preparadas no domic\u00edlio, com alimentos in natura, os valores de macronutrientes e energia podem corresponder a menos de 50% dos valores prescritos, resultando em uma administra\u00e7\u00e3o imprecisa dos nutrientes. Isso torna o paciente vulner\u00e1vel quanto \u00e0 seguran\u00e7a alimentar e agrava seu estado nutricional, podendo at\u00e9 complicar sua condi\u00e7\u00e3o cl\u00ednica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Outro fator importante \u00e9 que n\u00e3o h\u00e1 controle de osmolalidade e viscosidade no preparo de dietas artesanais e o desequil\u00edbrio desses dois fatores podem contribuir com complica\u00e7\u00f5es no sistema digestivo do paciente.<\/span><\/p>\n<p><b>A diferen\u00e7a entre a osmolalidade e a viscosidade<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A osmolalidade refere-se ao n\u00famero de part\u00edculas osmoticamente ativas de uma solu\u00e7\u00e3o e este fator \u00e9 de fundamental import\u00e2ncia na aceita\u00e7\u00e3o fisiol\u00f3gica pelos indiv\u00edduos submetidos \u00e0 nutri\u00e7\u00e3o enteral, al\u00e9m de estar relacionada com a via e o tipo de administra\u00e7\u00e3o da dieta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 a viscosidade \u00e9 a medida da resist\u00eancia ao movimento de um fluido e influencia na velocidade de aplica\u00e7\u00e3o das dietas enterais. Os nutrientes relacionados com a viscosidade da dieta s\u00e3o, principalmente, carboidratos e fibras. Ou seja, quanto maior ou menor a quantidade desses nutrientes, a dieta ser\u00e1 mais ou menos viscosa.<\/span><\/p>\n<p><b>Aposte em dietas enteral industrializadas<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Observamos, ent\u00e3o, que a nutri\u00e7\u00e3o enteral \u00e9 importante para manter ou recuperar o estado nutricional do paciente e, quando avaliamos o custo-benef\u00edcio, as dietas industrializadas se mostram como melhor op\u00e7\u00e3o, principalmente por apresentarem uma composi\u00e7\u00e3o nutricional mais completa, dispensando a necessidade de utiliza\u00e7\u00e3o de um complemento para atingimento das metas nutricionais, e menor necessidade de manipula\u00e7\u00e3o, reduzindo o risco de contamina\u00e7\u00e3o microbiol\u00f3gica e poss\u00edveis desfechos negativos ao paciente.<\/span><\/p>\n<p><b>Conte com a Nutrir Sa\u00fade<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A Nutrir Sa\u00fade conta com uma ampla gama de produtos para todas as idades, que contribuem para promover a sa\u00fade plena de todos. Por isso, temos os produtos ideais para ajudar voc\u00ea de acordo com as suas necessidades.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para conhecer mais nossos produtos e servi\u00e7os, clique <a href=\"https:\/\/api.whatsapp.com\/send?phone=558440089992&amp;text=Ol%C3%A1,%20tudo%20bem%3F%20Venho%20atrav%C3%A9s%20de%20um%20e-mail%20que%20recebi%20de%20voc%C3%AAs%20e%20gostaria%20de%20uma%20informa%C3%A7%C3%A3o,%20por%20favor.\" target=\"_blank\" rel=\"noopener\"><strong>aqui<\/strong><\/a> e fale conosco! <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conhe\u00e7a mais sobre a dieta enteral artesanal e a industrial e saiba qual \u00e9 a mais indicada para cada caso.<\/p>\n","protected":false},"author":3,"featured_media":697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[47],"tags":[57],"class_list":["post-1714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo","tag-dieta"],"acf":[],"_links":{"self":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/comments?post=1714"}],"version-history":[{"count":0,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1714\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/media?parent=1714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/categories?post=1714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/tags?post=1714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}