{"id":1711,"date":"2021-05-28T11:31:55","date_gmt":"2021-05-28T14:31:55","guid":{"rendered":"https:\/\/institucional.nutrirsaudestore.com.br\/?p=637"},"modified":"2021-05-28T11:31:55","modified_gmt":"2021-05-28T14:31:55","slug":"entenda-como-a-nutricao-auxilia-no-tratamento-de-doencas-inflamatorias-intestinais","status":"publish","type":"post","link":"https:\/\/nutrirsaudestore.com.br\/institucional\/entenda-como-a-nutricao-auxilia-no-tratamento-de-doencas-inflamatorias-intestinais\/","title":{"rendered":"Entenda como a nutri\u00e7\u00e3o auxilia no tratamento de doen\u00e7as inflamat\u00f3rias intestinais"},"content":{"rendered":"<p>Por: Louyse Diniz e Roseane Nabas<\/p>\n<p><span style=\"font-weight: 400;\">O m\u00eas de maio est\u00e1 chegando ao fim. Ainda assim, traz uma reflex\u00e3o importante que merece destaque o ano inteiro: estamos falando do Maio Roxo, que chama a aten\u00e7\u00e3o sobre diversas doen\u00e7as, como a Doen\u00e7a Inflamat\u00f3ria Intestinal.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pensando nesta importante campanha, decidimos falar um pouco mais sobre as Doen\u00e7as Inflamat\u00f3rias Intestinais e tamb\u00e9m como a Terapia Nutricional pode auxiliar no tratamento delas. Fique conosco e Leia Mais!\u00a0<\/span><\/p>\n<p><b>O que s\u00e3o as Doen\u00e7as Inflamat\u00f3rias Intestinais?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">As Doen\u00e7as Inflamat\u00f3rias Intestinais (DII) s\u00e3o caracterizadas pela exist\u00eancia de uma inflama\u00e7\u00e3o cr\u00f4nica, que tem como alvo preferencial o trato gastrointestinal, na por\u00e7\u00e3o do intestino onde ocorre a digest\u00e3o e a absor\u00e7\u00e3o de nutrientes,\u00a0 envolvendo frequentemente outros \u00f3rg\u00e3os e sistemas, com per\u00edodos ativos e outros de remiss\u00e3o. Dentre as principais doen\u00e7as desse grupo podemos destacar a Doen\u00e7a de Crohn (DC) e a Retocolite Ulcerativa (RU).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A RU e a DC apresentam manifesta\u00e7\u00f5es cl\u00ednicas semelhantes, como dores abdominais, diarr\u00e9ias recorrentes, sangue nas fezes, alguns epis\u00f3dios de febre, diminui\u00e7\u00e3o de apetite nos per\u00edodos de exacerba\u00e7\u00e3o da doen\u00e7a e risco aumentado para desenvolvimento de c\u00e2ncer de c\u00f3lon. No entanto, s\u00e3o distintas quanto \u00e0 sua localiza\u00e7\u00e3o: a DC pode ser observada ao longo de todo o trato gastrointestinal, enquanto que a RU se restringe ao intestino grosso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Devido aos seus in\u00edcios precoces, cursos da doen\u00e7a e a falta de cura e controle adequado para a maior parte dos indiv\u00edduos afetados, as DII apresentam um grande impacto negativo na qualidade de vida dos pacientes. Dessa maneira, a terapia nutricional visa reduzir sintomas desconfort\u00e1veis, repor fluidos perdidos, prevenir defici\u00eancias de vitaminas e minerais e fornecer uma ingest\u00e3o cal\u00f3rica adequada.<\/span><\/p>\n<p><b>A Terapia Nutricional no tratamento das Doen\u00e7as Inflamat\u00f3rias Intestinais<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Pacientes com DII apresentam diferentes intoler\u00e2ncias alimentares. Neste sentido, enquanto um paciente pode apresentar intoler\u00e2ncia a um certo alimento, outro n\u00e3o. Sendo assim, \u00e9 importante identificar alimentos que efetivamente ocasionam efeitos adversos e evitar consumi-los.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De uma maneira geral, deve-se manter uma dieta diversificada e rica em nutrientes. No entanto, na presen\u00e7a de sintomas, algumas dicas podem auxiliar no al\u00edvio:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Comer pequenas por\u00e7\u00f5es nas refei\u00e7\u00f5es;<br \/>\n<\/span><span style=\"font-weight: 400;\">&#8211; Fazer refei\u00e7\u00f5es mais frequentes;<br \/>\n<\/span><span style=\"font-weight: 400;\">&#8211; Comer em ambiente tranquilo;<br \/>\n<\/span><span style=\"font-weight: 400;\">&#8211; Evitar alimentos desencadeantes;<br \/>\n<\/span><span style=\"font-weight: 400;\">&#8211; Limitar alimentos com fibras insol\u00faveis (isto \u00e9, sementes, gr\u00e3os, vegetais de folhas verdes, frutas laxativas e farelo de trigo);<br \/>\n<\/span><span style=\"font-weight: 400;\">&#8211; Reduzir a quantidade de alimentos gordurosos ou fritos.\u00a0<\/span><\/p>\n<p><b>Aposte na ingest\u00e3o h\u00eddrica. Evite alguns tipos de fibras!<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 importante manter uma boa ingest\u00e3o h\u00eddrica, principalmente quando houver quadros de diarreia, pois pode haver risco de desidrata\u00e7\u00e3o. Alguns l\u00edquidos, como \u00e1gua de coco ou soro caseiro, podem auxiliar na reposi\u00e7\u00e3o de eletr\u00f3litos perdidos em casos de diarreia grave.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao ingerir o l\u00edquido, o paciente deve evitar o uso de canudos e beber lentamente, pois, assim, evita desconfortos causados pela entrada de ar no sistema digestivo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O consumo de fibras nos per\u00edodos de crise pode ocasionar c\u00f3licas abdominais, incha\u00e7os e diarreias em algumas pessoas. No entanto, algumas fibras podem ajudar na redu\u00e7\u00e3o dos sintomas, e para isso \u00e9 importante conhecer os diferentes tipos de fibras.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A fibra sol\u00favel possui a capacidade de reter \u00e1gua e reduzir o tempo de perman\u00eancia dos alimentos no intestino, dessa maneira ela auxilia na redu\u00e7\u00e3o da diarr\u00e9ia. J\u00e1 a fibra insol\u00favel n\u00e3o possui essa capacidade de reter \u00e1gua e \u00e9 mais dif\u00edcil de digerir, fazendo o alimento se mover mais rapidamente pelo intestino.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dessa maneira, pode agravar os sintomas, especialmente quando h\u00e1 inflama\u00e7\u00e3o grave. A maioria dos alimentos cont\u00e9m uma combina\u00e7\u00e3o de fibras, por isso, pacientes em crise devem cozinhar, descascar e remover sementes e gr\u00e3os como alternativa para reduzir a ingest\u00e3o de fibras insol\u00faveis.<\/span><\/p>\n<p><b>Cuidado: atente-se \u00e0 absor\u00e7\u00e3o ideal dos nutrientes\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Pacientes com inflama\u00e7\u00e3o no intestino podem ter interfer\u00eancia tamb\u00e9m na absor\u00e7\u00e3o de nutrientes, o que chamamos de m\u00e1 absor\u00e7\u00e3o. Os amino\u00e1cidos (das prote\u00ednas), \u00e1cidos graxos (das gorduras), a\u00e7\u00facares (dos carboidratos), vitaminas e minerais s\u00e3o absorvidos principalmente nas duas \u00faltimas partes do intestino delgado (jejuno e \u00edleo).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A m\u00e1 absor\u00e7\u00e3o e as defici\u00eancias de nutrientes tendem a ser mais significativas quando as maiores partes do intestino est\u00e3o inflamadas ou precisam ser removidas cirurgicamente.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com rela\u00e7\u00e3o, principalmente ao grupo das prote\u00ednas, as pessoas com DII precisar\u00e3o comer quantidades aumentadas deste macronutriente quando t\u00eam inflama\u00e7\u00e3o ou quando se recuperam dela.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os tipos de prote\u00ednas animais (peixe, carne bovina, porco, aves, ovos e latic\u00ednios) cont\u00eam todos os amino\u00e1cidos essenciais; enquanto as fontes vegetais de prote\u00edna podem n\u00e3o conter todos os amino\u00e1cidos, mas ser consumidas em combina\u00e7\u00e3o para fornecer todas as prote\u00ednas necess\u00e1rias.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Importante sempre escolher cortes de carne magra ou com pouca gordura e aves, principalmente, durante as crises da doen\u00e7a, porque o excesso de gordura pode levar \u00e0 m\u00e1 absor\u00e7\u00e3o, al\u00e9m de piorar os sintomas indesej\u00e1veis.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre outras fontes proteicas, incluem-se os produtos \u00e0 base de soja, legumes e gr\u00e3os. Carnes, frutos do mar, leguminosas (feij\u00f5es, gr\u00e3o de bico, soja, ervilha, soja), ovos, s\u00e3o excelentes fontes de prote\u00edna e tamb\u00e9m fornecem vitaminas e minerais.\u00a0<\/span><\/p>\n<p><b>Mantenha a boa nutri\u00e7\u00e3o: cuide da sua sa\u00fade!<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A presen\u00e7a de uma DII ativa, como a DC ou a RC, tende a aumentar os requisitos de calorias, nutrientes e energia do organismo. Durante os momentos de crises das doen\u00e7as, pode ser dif\u00edcil manter a nutri\u00e7\u00e3o adequada. Mas manter uma boa nutri\u00e7\u00e3o ajuda a melhorar o bem-estar geral, promover a cicatriza\u00e7\u00e3o e aumentar a imunidade, elevar os n\u00edveis de energia, al\u00e9m de aliviar alguns sintomas gastrointestinais.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Muitos indiv\u00edduos com DII podem consumir uma dieta normal durante os per\u00edodos de remiss\u00e3o da doen\u00e7a, mas precisam de um cuidado especial durante as crises.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dessa forma, o planejamento alimentar adequado deve sempre levar em considera\u00e7\u00e3o os seguintes aspectos:\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Sintomas apresentados (diarreia, constipa\u00e7\u00e3o, dor abdominal, entre outros);<br \/>\n<\/span><span style=\"font-weight: 400;\">&#8211; Localiza\u00e7\u00e3o da doen\u00e7a\/inflama\u00e7\u00e3o; presen\u00e7a ou n\u00e3o de estreitamento no intestino delgado (estenoses);<br \/>\n<\/span><span style=\"font-weight: 400;\">&#8211; Se j\u00e1 teve alguma cirurgia pr\u00e9via e a presen\u00e7a de defici\u00eancias nutricionais espec\u00edficas (como a de ferro, por exemplo).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se o m\u00e9todo normal de ingest\u00e3o de alimentos por via oral n\u00e3o estiver possibilitando o aporte cal\u00f3rico e absor\u00e7\u00e3o suficiente de nutrientes, faz-se necess\u00e1rio considerar outros m\u00e9todos para nutri\u00e7\u00e3o desses indiv\u00edduos, como por exemplo a nutri\u00e7\u00e3o enteral e\/ou a nutri\u00e7\u00e3o parenteral. Quando se torna necess\u00e1rio esse consumo de calorias extras ricas em nutrientes, essa suplementa\u00e7\u00e3o pode ser obtida por meio de f\u00f3rmulas que cont\u00eam quantidades equilibradas de prote\u00ednas, carboidratos, gorduras e vitaminas, sendo de suma import\u00e2ncia a orienta\u00e7\u00e3o e acompanhamento nutricional por meio de um profissional capacitado.\u00a0<\/span><\/p>\n<p><b>Tenha acompanhamento com profissionais especializados<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Para seguir uma alimenta\u00e7\u00e3o adequada, evitando ou tratando as Doen\u00e7as Inflamat\u00f3rias Intestinais, \u00e9 fundamental ter o acompanhamento de nutricionistas, profissionais estes capacitados e especializados na \u00e1rea, indicando as melhores dietas e alimentos para ingest\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As nutricionistas da Nutrir Sa\u00fade est\u00e3o prontas para atender voc\u00ea! Clique <a href=\"https:\/\/api.whatsapp.com\/send?phone=558440089992&amp;text=Ol%C3%A1,%20tudo%20bem%3F%20Venho%20atrav%C3%A9s%20de%20um%20e-mail%20que%20recebi%20de%20voc%C3%AAs%20e%20gostaria%20de%20uma%20informa%C3%A7%C3%A3o,%20por%20favor.\" target=\"_blank\" rel=\"noopener\"><strong>aqui<\/strong><\/a>, fale conosco e saiba como podemos ajudar.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A alimenta\u00e7\u00e3o adequada e nutricional \u00e9 fundamental para evitar doen\u00e7as inflamat\u00f3rias intestinais. Saiba Mais!<\/p>\n","protected":false},"author":3,"featured_media":638,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[47],"tags":[65,66,58],"class_list":["post-1711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo","tag-doencas","tag-nutricao","tag-nutricao-clinica-e-terapeutica"],"acf":[],"_links":{"self":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/comments?post=1711"}],"version-history":[{"count":0,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/posts\/1711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/elementor_library\/638"}],"wp:attachment":[{"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/media?parent=1711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/categories?post=1711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutrirsaudestore.com.br\/institucional\/wp-json\/wp\/v2\/tags?post=1711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}